{"id":4370,"date":"2019-01-16T17:41:21","date_gmt":"2019-01-16T20:41:21","guid":{"rendered":"http:\/\/dev.acervapaulista.com.br\/?page_id=4370"},"modified":"2025-10-29T13:41:08","modified_gmt":"2025-10-29T16:41:08","slug":"por-que-me-associar","status":"publish","type":"page","link":"https:\/\/acervapaulista.com.br\/wordpress\/por-que-me-associar\/","title":{"rendered":"Por que me associar?"},"content":{"rendered":"<div id=\"cs-content\" class=\"cs-content\"><div class=\"x-section e4370-e1 m3de-0\"><div class=\"x-container marginless-columns e4370-e2 m3de-1\"><div class=\"x-column x-sm x-2-3 e4370-e3 m3de-2\"><div class=\"x-text x-content e4370-e4 m3de-3 m3de-4\"><p><span>Associe-se \u00e0 <strong>ACervA Paulista<\/strong> e desfrute de momentos \u00fanicos de <strong>confraterniza\u00e7\u00e3o e aprendizado<\/strong>, em que s\u00f3 quem faz cerveja poder\u00e1 compartilhar com voc\u00ea. Ao se tornar s\u00f3cio, al\u00e9m de ajudar a fortalecer nossa associa\u00e7\u00e3o e a cultura de cerveja caseira, voc\u00ea ter\u00e1 os <strong>seguintes benef\u00edcios<\/strong>:<br \/><br \/><\/span><\/p><\/div><ul  class=\"x-feature-list\"  data-x-element=\"feature_list\" data-x-params=\"{&quot;animationOffset&quot;:&quot;50&quot;,&quot;animationDelayInitial&quot;:&quot;0&quot;,&quot;animationDelayBetween&quot;:&quot;300&quot;}\"><li  class=\"x-feature-box left-text top-text cf\" style=\" max-width: none;\" data-x-element=\"feature_box\" data-x-params=\"{&quot;child&quot;:true,&quot;graphicAnimation&quot;:&quot;none&quot;,&quot;connectorAnimation&quot;:&quot;none&quot;,&quot;alignH&quot;:&quot;left&quot;,&quot;alignV&quot;:&quot;top&quot;}\"><span class=\"x-feature-box-connector full\" style=\"font-size: 60px; left: 0; right: calc(100% - 60px); border-left: 1px dashed hsl(44, 97%, 14%);\"><\/span><div class=\"x-feature-box-graphic circle \"><div class=\"x-feature-box-graphic-outer circle\" style=\" margin-right: 20px;\"><div class=\"x-feature-box-graphic-inner circle\" style=\"font-size: 60px;\"><i class=\"x-icon-beer circle\" data-x-icon-s=\"&#xf0fc;\"  style=\"margin: 0 auto; color: #ffffff; background-color: hsl(46, 98%, 17%);\"><\/i><\/div><\/div><\/div><div class=\"x-feature-box-content \"><h4 class=\"x-feature-box-title\">Eventos<\/h4><p class=\"x-feature-box-text\"><b>Brassagens abertas<\/b> entre s\u00f3cios ou com cervejeiros profissionais; <br><b>Concursos homologados<\/b> BJCP com premia\u00e7\u00f5es aos primeiros colocados;<br><b>Festas e encontros<\/b> de s\u00f3cios, com degusta\u00e7\u00f5es de v\u00e1rios estilos de cerveja.<\/p><\/div><\/li><li  class=\"x-feature-box left-text top-text cf\" style=\" max-width: none;\" data-x-element=\"feature_box\" data-x-params=\"{&quot;child&quot;:true,&quot;graphicAnimation&quot;:&quot;none&quot;,&quot;connectorAnimation&quot;:&quot;none&quot;,&quot;alignH&quot;:&quot;left&quot;,&quot;alignV&quot;:&quot;top&quot;}\"><span class=\"x-feature-box-connector full\" style=\"font-size: 60px; left: 0; right: calc(100% - 60px); border-left: 1px dashed hsl(44, 97%, 14%);\"><\/span><div class=\"x-feature-box-graphic circle \"><div class=\"x-feature-box-graphic-outer circle\" style=\" margin-right: 20px;\"><div class=\"x-feature-box-graphic-inner circle\" style=\"font-size: 60px;\"><i class=\"x-icon-graduation-cap circle\" data-x-icon-s=\"&#xf19d;\"  style=\"margin: 0 auto; color: #ffffff; background-color: hsl(16, 87%, 39%);\"><\/i><\/div><\/div><\/div><div class=\"x-feature-box-content \"><h4 class=\"x-feature-box-title\">Educa\u00e7\u00e3o<\/h4><p class=\"x-feature-box-text\"><b>Cursos e workshops<\/b> internos e com parceiros;<br><b>Grupo de discuss\u00e3o<\/b> entre membros para troca de experi\u00eancias;<br><b>Grupos de estudo<\/b> cervejeiro (ex: avalia\u00e7\u00e3o de cervejas baseado no BJCP);<br>Painel sensorial (sabatinada) para <b>avalia\u00e7\u00e3o de cervejas<\/b>.<\/p><\/div><\/li><li  class=\"x-feature-box left-text top-text cf\" style=\" max-width: none;\" data-x-element=\"feature_box\" data-x-params=\"{&quot;child&quot;:true,&quot;graphicAnimation&quot;:&quot;none&quot;,&quot;connectorAnimation&quot;:&quot;none&quot;,&quot;alignH&quot;:&quot;left&quot;,&quot;alignV&quot;:&quot;top&quot;}\"><span class=\"x-feature-box-connector full\" style=\"font-size: 60px; left: 0; right: calc(100% - 60px); border-left: 1px dashed hsl(44, 97%, 14%);\"><\/span><div class=\"x-feature-box-graphic circle \"><div class=\"x-feature-box-graphic-outer circle\" style=\" margin-right: 20px;\"><div class=\"x-feature-box-graphic-inner circle\" style=\"font-size: 60px;\"><i class=\"x-icon-dollar circle\" data-x-icon-s=\"&#x24;\"  style=\"margin: 0 auto; color: #ffffff; background-color: hsl(65, 93%, 46%);\"><\/i><\/div><\/div><\/div><div class=\"x-feature-box-content \"><h4 class=\"x-feature-box-title\">Financeiro<\/h4><p class=\"x-feature-box-text\">Descontos em compras de <b>Insumos e Equipamentos<\/b> em nossos Parceiros;<br>Descontos em <b>cursos e workshops<\/b> internos e de parceiros.<\/p><\/div><\/li><\/ul><div class=\"x-text x-content e4370-e9 m3de-3 m3de-4\"><h5><span style=\"color: #808000;\">Perguntas e Respostas<\/span><\/h5><p><\/p><\/div><div  class=\"x-accordion\" ><div  class=\"x-accordion-group\" ><div class=\"x-accordion-heading\"><a id=\"tab-6a56d0ca34d13\" class=\"x-accordion-toggle collapsed\" role=\"tab\" data-x-toggle=\"collapse-b\" data-x-toggleable=\"6a56d0ca34d13\" aria-selected=\"false\" aria-expanded=\"false\" aria-controls=\"panel-6a56d0ca34d13\"><i class='x-framework-icon x-shortcode-accordion-icon' data-x-icon-s='&#x2b;' aria-hidden=true><\/i><span>Qual a taxa de associa\u00e7\u00e3o?<\/span><\/a><\/div><div id=\"panel-6a56d0ca34d13\" class=\"x-accordion-body x-collapsed\" role=\"tabpanel\" data-x-toggle-collapse=\"1\" data-x-toggleable=\"6a56d0ca34d13\" aria-hidden=\"true\" aria-labelledby=\"tab-6a56d0ca34d13\"><div class=\"x-accordion-inner\"><div class=\"x-accordion-group\">\n<div id=\"panel-5c449b2989bb9\" class=\"x-accordion-body\" role=\"tabpanel\" data-x-toggle-collapse=\"1\" data-x-toggleable=\"5c449b2989bb9\" aria-hidden=\"false\" aria-labelledby=\"tab-5c449b2989bb9\">\n<div class=\"x-accordion-inner\">\n<p>\u00c9 cobrada uma colabora\u00e7\u00e3o de cada s\u00f3cio com o objetivo de desenvolver a associa\u00e7\u00e3o, pagar impostos, manter alguns dos benef\u00edcios oferecidos e o que mais for necess\u00e1rio.<\/p>\n<p>Temos a seguinte pol\u00edtica de pagamentos de colabora\u00e7\u00e3o:<\/p>\n\n<ul>\n \t<li>Semestral: R$ 160,00<\/li>\n \t<li>Anual*: R$ 240,00<\/li>\n \t<li>Renova\u00e7\u00e3o anual com desconto de pontualidade*: R$ 180,00<\/li>\n<\/ul>\n<p>*12 meses \u00e9 o limite m\u00e1ximo para pagamentos.<\/p>\n\n<\/div>\n<\/div>\n<\/div>\n<div class=\"x-accordion-group\">\n<div class=\"x-accordion-heading\"><\/div>\n<\/div><\/div><\/div><\/div><div  class=\"x-accordion-group\" ><div class=\"x-accordion-heading\"><a id=\"tab-6a56d0ca34d27\" class=\"x-accordion-toggle collapsed\" role=\"tab\" data-x-toggle=\"collapse-b\" data-x-toggleable=\"6a56d0ca34d27\" aria-selected=\"false\" aria-expanded=\"false\" aria-controls=\"panel-6a56d0ca34d27\"><i class='x-framework-icon x-shortcode-accordion-icon' data-x-icon-s='&#x2b;' aria-hidden=true><\/i><span>Por que existe a taxa?<\/span><\/a><\/div><div id=\"panel-6a56d0ca34d27\" class=\"x-accordion-body x-collapsed\" role=\"tabpanel\" data-x-toggle-collapse=\"1\" data-x-toggleable=\"6a56d0ca34d27\" aria-hidden=\"true\" aria-labelledby=\"tab-6a56d0ca34d27\"><div class=\"x-accordion-inner\"><p><span>Administrar uma associa\u00e7\u00e3o s\u00e9ria do porte da ACervA Paulista gera custos. Uma entidade estruturada, com um sistema administrativo forte e espalhada por um estado do tamanho de S\u00e3o Paulo e que demanda alguns custos operacionais como:<\/span><\/p><ul><li>Aluguel da sede\u00a0(a associa\u00e7\u00e3o est\u00e1 temporariamente sem uma sede fixa);<\/li><li>Aluguel de espa\u00e7os para encontros\/ workshops\/ degusta\u00e7\u00f5es;<\/li><li>Material de publicidade para fazer cumprir a miss\u00e3o da ACervA Paulista;<\/li><li>Custos dos encontros de s\u00f3cios;<\/li><li>Ajudar no custo de fabrica\u00e7\u00e3o de cervejas dos s\u00f3cios para encontros da associa\u00e7\u00e3o;<\/li><li>Manute\u00e7\u00e3o do site;<\/li><li>Custos para tr\u00e2mites legais da associa\u00e7\u00e3o (advogado, contador, cart\u00f3rio);<\/li><li>Entre outros.<\/li><\/ul><p>A\u00a0ACervA Paulista \u00e9 mantida por s\u00f3cios volunt\u00e1rios e que ajudam a disseminar a cultura cervejeira e gerir todas as necessidades da associa\u00e7\u00e3o.<\/p><\/div><\/div><\/div><div  class=\"x-accordion-group\" ><div class=\"x-accordion-heading\"><a id=\"tab-6a56d0ca34d33\" class=\"x-accordion-toggle collapsed\" role=\"tab\" data-x-toggle=\"collapse-b\" data-x-toggleable=\"6a56d0ca34d33\" aria-selected=\"false\" aria-expanded=\"false\" aria-controls=\"panel-6a56d0ca34d33\"><i class='x-framework-icon x-shortcode-accordion-icon' data-x-icon-s='&#x2b;' aria-hidden=true><\/i><span>Quando terei os benef\u00edcios?<\/span><\/a><\/div><div id=\"panel-6a56d0ca34d33\" class=\"x-accordion-body x-collapsed\" role=\"tabpanel\" data-x-toggle-collapse=\"1\" data-x-toggleable=\"6a56d0ca34d33\" aria-hidden=\"true\" aria-labelledby=\"tab-6a56d0ca34d33\"><div class=\"x-accordion-inner\"><p><span>A partir do primeiro dia do recebimento da sua inscri\u00e7\u00e3o, voc\u00ea j\u00e1 ter\u00e1 seu perfil de s\u00f3cio associado ao seu usu\u00e1rio e poder\u00e1 ter acesso a biblioteca, participar dos eventos e entrar em nosso grupo de discuss\u00e3o no WhatsApp.<\/span><\/p><p>Descontos e outros benef\u00edcios tamb\u00e9m ser\u00e3o imediatamente ap\u00f3s o recebimento, pois os parceiros s\u00e3o orientados a consultar a carteirinha atualizada dos s\u00f3cios sempre que um desconto for solicitado.<\/p>\n<p>Estas informa\u00e7\u00f5es estar\u00e3o no menu \"\u00c1rea do S\u00f3cio\".<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"x-column x-sm x-1-3 e4370-e14 m3de-2\"><div class=\"x-text x-text-headline e4370-e15 m3de-6\"><div class=\"x-text-content\"><div class=\"x-text-content-text\"><h2 class=\"x-text-content-text-primary\">Vem pra ACervA!<\/h2>\n<\/div><\/div><\/div><div class=\"x-text x-content e4370-e16 m3de-3 m3de-5\"><p>Pague agora a sua associa\u00e7\u00e3o utilizando uma das op\u00e7\u00f5es abaixo:<\/p><\/div><hr class=\"x-line e4370-e17 m3de-7 m3de-8\"\/><a class=\"x-anchor x-anchor-button has-graphic e4370-e18 m3de-a\" tabindex=\"0\" href=\"https:\/\/acervapaulista.com.br\/wordpress\/loja\/associacao-anual\/\"><div class=\"x-anchor-content\"><span class=\"x-graphic\" aria-hidden=\"true\"><i class=\"x-icon x-graphic-child x-graphic-icon x-graphic-primary\" aria-hidden=\"true\" data-x-icon-s=\"&#xf07a;\"><\/i><\/span><div class=\"x-anchor-text\"><span class=\"x-anchor-text-primary\">Associa\u00e7\u00e3o Anual<\/span><span class=\"x-anchor-text-secondary\">R$ 240,00<\/span><\/div><\/div><\/a><a class=\"x-anchor x-anchor-button has-graphic e4370-e19 m3de-a\" tabindex=\"0\" href=\"https:\/\/acervapaulista.com.br\/wordpress\/loja\/associacao-semestral\/\"><div class=\"x-anchor-content\"><span class=\"x-graphic\" aria-hidden=\"true\"><i class=\"x-icon x-graphic-child x-graphic-icon x-graphic-primary\" aria-hidden=\"true\" data-x-icon-s=\"&#xf07a;\"><\/i><\/span><div class=\"x-anchor-text\"><span class=\"x-anchor-text-primary\">Associa\u00e7\u00e3o Semestral<\/span><span class=\"x-anchor-text-secondary\">R$ 160,00<\/span><\/div><\/div><\/a><hr class=\"x-line e4370-e20 m3de-8 m3de-9\"\/><span class=\"x-image e4370-e21 m3de-b m3de-c\"><img decoding=\"async\" src=\"http:\/\/acervapaulista.com.br\/wordpress\/wp-content\/uploads\/2019\/06\/Nacional-2019-Galera-01.jpg\" width=\"640\" height=\"480\" alt=\"Image\" loading=\"lazy\"><\/span><hr class=\"x-line e4370-e22 m3de-8 m3de-9\"\/><span class=\"x-image e4370-e23 m3de-b m3de-d\"><img decoding=\"async\" src=\"https:\/\/acervapaulista.com.br\/wordpress\/wp-content\/uploads\/2023\/01\/IMG-20221210-WA0079.jpg\" width=\"1600\" height=\"900\" alt=\"Image\" loading=\"lazy\"><\/span><hr class=\"x-line e4370-e24 m3de-8 m3de-9\"\/><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Associe-se \u00e0 ACervA Paulista e desfrute de momentos \u00fanicos de confraterniza\u00e7\u00e3o e aprendizado, em que s\u00f3 quem faz cerveja poder\u00e1 compartilhar com voc\u00ea. Ao se tornar s\u00f3cio, al\u00e9m de ajudar a fortalecer nossa associa\u00e7\u00e3o e a cultura de cerveja caseira, voc\u00ea ter\u00e1 os seguintes benef\u00edcios:EventosBrassagens abertas entre s\u00f3cios ou com cervejeiros profissionais; Concursos homologados BJCP com premia\u00e7\u00f5es aos primeiros colocados;Festas e encontros de s\u00f3cios, com degusta\u00e7\u00f5es de v\u00e1rios estilos de cerveja.Educa\u00e7\u00e3oCursos e workshops internos e com parceiros;Grupo de discuss\u00e3o entre membros para troca de experi\u00eancias;Grupos de estudo cervejeiro (ex: avalia\u00e7\u00e3o de cervejas baseado no BJCP);Painel sensorial (sabatinada) para avalia\u00e7\u00e3o de cervejas.FinanceiroDescontos em compras de Insumos e Equipamentos em nossos Parceiros;Descontos em cursos e workshops internos e de parceiros.Perguntas e RespostasQual a taxa de associa\u00e7\u00e3o? \u00c9 cobrada uma colabora\u00e7\u00e3o de cada s\u00f3cio com o objetivo de desenvolver a associa\u00e7\u00e3o, pagar impostos, manter alguns dos benef\u00edcios oferecidos e o que mais for necess\u00e1rio. Temos a seguinte pol\u00edtica de pagamentos de colabora\u00e7\u00e3o: Semestral: R$ 160,00 Anual*: R$ 240,00 Renova\u00e7\u00e3o anual com desconto de pontualidade*: R$ 180,00 *12 meses \u00e9 o limite m\u00e1ximo para pagamentos. Por que existe a taxa?Administrar uma associa\u00e7\u00e3o s\u00e9ria do porte da ACervA Paulista gera custos. Uma entidade estruturada, com &#8230; <a href=\"https:\/\/acervapaulista.com.br\/wordpress\/por-que-me-associar\/\" class=\"more-link\">Read More<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-layout-content-sidebar.php","meta":{"pmpro_default_level":"","_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"class_list":["post-4370","page","type-page","status-publish","hentry","pmpro-has-access","no-post-thumbnail"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/pages\/4370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/comments?post=4370"}],"version-history":[{"count":24,"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/pages\/4370\/revisions"}],"predecessor-version":[{"id":8364,"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/pages\/4370\/revisions\/8364"}],"wp:attachment":[{"href":"https:\/\/acervapaulista.com.br\/wordpress\/wp-json\/wp\/v2\/media?parent=4370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}